{"id":1688,"date":"1714-09-07T18:30:29","date_gmt":"1714-09-07T17:30:29","guid":{"rendered":"https:\/\/centrumjudaicum.de\/?p=1688"},"modified":"2023-08-24T09:37:03","modified_gmt":"2023-08-24T07:37:03","slug":"dies-ist-eine-ueberschrift-4","status":"publish","type":"post","link":"https:\/\/centrumjudaicum.de\/en\/dies-ist-eine-ueberschrift-4\/","title":{"rendered":"September 7, 1714 <br class=\"clear\" \/> Einweihung Gemeindesynagoge Heidereutergasse"},"content":{"rendered":"<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/centrumjudaicum.de\/wp-content\/uploads\/1714\/09\/Bild-2_Synagoge-Heidereuthergasse_innen_c-CJ-WAkl-2.jpg\" alt=\"\" class=\"wp-image-15337\" style=\"width:394px;height:394px\" width=\"394\" height=\"394\" srcset=\"https:\/\/centrumjudaicum.de\/wp-content\/uploads\/1714\/09\/Bild-2_Synagoge-Heidereuthergasse_innen_c-CJ-WAkl-2.jpg 263w, https:\/\/centrumjudaicum.de\/wp-content\/uploads\/1714\/09\/Bild-2_Synagoge-Heidereuthergasse_innen_c-CJ-WAkl-2-150x150.jpg 150w\" sizes=\"(max-width: 394px) 100vw, 394px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Consecration of the first synagogue building in Berlin at Heidereutergasse.<\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Consecration of the first synagogue building in Berlin at Heidereutergasse.<\/p>","protected":false},"author":1,"featured_media":15337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_tec_requires_first_save":true,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"categories":[14],"tags":[],"class_list":["post-1688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-zeittafel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>7. September 1714  Einweihung Gemeindesynagoge Heidereutergasse - Centrum Judaicum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrumjudaicum.de\/en\/dies-ist-eine-ueberschrift-4\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7. September 1714  Einweihung Gemeindesynagoge Heidereutergasse\" \/>\n<meta property=\"og:description\" content=\"Einweihung der ersten Gemeindesynagoge in der Heidereutergasse\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrumjudaicum.de\/en\/dies-ist-eine-ueberschrift-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Centrum Judaicum\" \/>\n<meta property=\"article:published_time\" content=\"1714-09-07T17:30:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-24T07:37:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrumjudaicum.de\/wp-content\/uploads\/1714\/09\/Bild-2_Synagoge-Heidereuthergasse_innen_c-CJ-WAkl-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"263\" \/>\n\t<meta property=\"og:image:height\" content=\"263\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"wpadmin2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"wpadmin2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrumjudaicum.de\\\/dies-ist-eine-ueberschrift-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrumjudaicum.de\\\/dies-ist-eine-ueberschrift-4\\\/\"},\"author\":{\"name\":\"wpadmin2\",\"@id\":\"https:\\\/\\\/centrumjudaicum.de\\\/#\\\/schema\\\/person\\\/92a9897d9fc5452e4e01ff70c2fa760d\"},\"headline\":\"7. September 1714 Einweihung Gemeindesynagoge Heidereutergasse\",\"datePublished\":\"1714-09-07T17:30:29+00:00\",\"dateModified\":\"2023-08-24T07:37:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrumjudaicum.de\\\/dies-ist-eine-ueberschrift-4\\\/\"},\"wordCount\":11,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrumjudaicum.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrumjudaicum.de\\\/dies-ist-eine-ueberschrift-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrumjudaicum.de\\\/wp-content\\\/uploads\\\/1714\\\/09\\\/Bild-2_Synagoge-Heidereuthergasse_innen_c-CJ-WAkl-2.jpg\",\"articleSection\":[\"Zeittafel\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrumjudaicum.de\\\/dies-ist-eine-ueberschrift-4\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrumjudaicum.de\\\/dies-ist-eine-ueberschrift-4\\\/\",\"url\":\"https:\\\/\\\/centrumjudaicum.de\\\/dies-ist-eine-ueberschrift-4\\\/\",\"name\":\"7. September 1714 Einweihung Gemeindesynagoge Heidereutergasse - Centrum Judaicum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrumjudaicum.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrumjudaicum.de\\\/dies-ist-eine-ueberschrift-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrumjudaicum.de\\\/dies-ist-eine-ueberschrift-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrumjudaicum.de\\\/wp-content\\\/uploads\\\/1714\\\/09\\\/Bild-2_Synagoge-Heidereuthergasse_innen_c-CJ-WAkl-2.jpg\",\"datePublished\":\"1714-09-07T17:30:29+00:00\",\"dateModified\":\"2023-08-24T07:37:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrumjudaicum.de\\\/dies-ist-eine-ueberschrift-4\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrumjudaicum.de\\\/dies-ist-eine-ueberschrift-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/centrumjudaicum.de\\\/dies-ist-eine-ueberschrift-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrumjudaicum.de\\\/wp-content\\\/uploads\\\/1714\\\/09\\\/Bild-2_Synagoge-Heidereuthergasse_innen_c-CJ-WAkl-2.jpg\",\"contentUrl\":\"https:\\\/\\\/centrumjudaicum.de\\\/wp-content\\\/uploads\\\/1714\\\/09\\\/Bild-2_Synagoge-Heidereuthergasse_innen_c-CJ-WAkl-2.jpg\",\"width\":263,\"height\":263},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrumjudaicum.de\\\/dies-ist-eine-ueberschrift-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/centrumjudaicum.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"7. September 1714 Einweihung Gemeindesynagoge Heidereutergasse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrumjudaicum.de\\\/#website\",\"url\":\"https:\\\/\\\/centrumjudaicum.de\\\/\",\"name\":\"Centrum Judaicum\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrumjudaicum.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrumjudaicum.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrumjudaicum.de\\\/#organization\",\"name\":\"Centrum Judaicum\",\"url\":\"https:\\\/\\\/centrumjudaicum.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/centrumjudaicum.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrumjudaicum.de\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Logo_Stiftung_Neue_Synagoge_Berlin_Gold_.png\",\"contentUrl\":\"https:\\\/\\\/centrumjudaicum.de\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Logo_Stiftung_Neue_Synagoge_Berlin_Gold_.png\",\"width\":1188,\"height\":409,\"caption\":\"Centrum Judaicum\"},\"image\":{\"@id\":\"https:\\\/\\\/centrumjudaicum.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrumjudaicum.de\\\/#\\\/schema\\\/person\\\/92a9897d9fc5452e4e01ff70c2fa760d\",\"name\":\"wpadmin2\",\"sameAs\":[\"https:\\\/\\\/centrumjudaicum.de\"],\"url\":\"https:\\\/\\\/centrumjudaicum.de\\\/en\\\/author\\\/wpadmin2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"7. September 1714  Einweihung Gemeindesynagoge Heidereutergasse - Centrum Judaicum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrumjudaicum.de\/en\/dies-ist-eine-ueberschrift-4\/","og_locale":"en_US","og_type":"article","og_title":"7. September 1714  Einweihung Gemeindesynagoge Heidereutergasse","og_description":"Einweihung der ersten Gemeindesynagoge in der Heidereutergasse","og_url":"https:\/\/centrumjudaicum.de\/en\/dies-ist-eine-ueberschrift-4\/","og_site_name":"Centrum Judaicum","article_published_time":"1714-09-07T17:30:29+00:00","article_modified_time":"2023-08-24T07:37:03+00:00","og_image":[{"width":263,"height":263,"url":"https:\/\/centrumjudaicum.de\/wp-content\/uploads\/1714\/09\/Bild-2_Synagoge-Heidereuthergasse_innen_c-CJ-WAkl-2.jpg","type":"image\/jpeg"}],"author":"wpadmin2","twitter_card":"summary_large_image","twitter_misc":{"Written by":"wpadmin2","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrumjudaicum.de\/dies-ist-eine-ueberschrift-4\/#article","isPartOf":{"@id":"https:\/\/centrumjudaicum.de\/dies-ist-eine-ueberschrift-4\/"},"author":{"name":"wpadmin2","@id":"https:\/\/centrumjudaicum.de\/#\/schema\/person\/92a9897d9fc5452e4e01ff70c2fa760d"},"headline":"7. September 1714 Einweihung Gemeindesynagoge Heidereutergasse","datePublished":"1714-09-07T17:30:29+00:00","dateModified":"2023-08-24T07:37:03+00:00","mainEntityOfPage":{"@id":"https:\/\/centrumjudaicum.de\/dies-ist-eine-ueberschrift-4\/"},"wordCount":11,"commentCount":0,"publisher":{"@id":"https:\/\/centrumjudaicum.de\/#organization"},"image":{"@id":"https:\/\/centrumjudaicum.de\/dies-ist-eine-ueberschrift-4\/#primaryimage"},"thumbnailUrl":"https:\/\/centrumjudaicum.de\/wp-content\/uploads\/1714\/09\/Bild-2_Synagoge-Heidereuthergasse_innen_c-CJ-WAkl-2.jpg","articleSection":["Zeittafel"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrumjudaicum.de\/dies-ist-eine-ueberschrift-4\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrumjudaicum.de\/dies-ist-eine-ueberschrift-4\/","url":"https:\/\/centrumjudaicum.de\/dies-ist-eine-ueberschrift-4\/","name":"7. September 1714 Einweihung Gemeindesynagoge Heidereutergasse - Centrum Judaicum","isPartOf":{"@id":"https:\/\/centrumjudaicum.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrumjudaicum.de\/dies-ist-eine-ueberschrift-4\/#primaryimage"},"image":{"@id":"https:\/\/centrumjudaicum.de\/dies-ist-eine-ueberschrift-4\/#primaryimage"},"thumbnailUrl":"https:\/\/centrumjudaicum.de\/wp-content\/uploads\/1714\/09\/Bild-2_Synagoge-Heidereuthergasse_innen_c-CJ-WAkl-2.jpg","datePublished":"1714-09-07T17:30:29+00:00","dateModified":"2023-08-24T07:37:03+00:00","breadcrumb":{"@id":"https:\/\/centrumjudaicum.de\/dies-ist-eine-ueberschrift-4\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrumjudaicum.de\/dies-ist-eine-ueberschrift-4\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/centrumjudaicum.de\/dies-ist-eine-ueberschrift-4\/#primaryimage","url":"https:\/\/centrumjudaicum.de\/wp-content\/uploads\/1714\/09\/Bild-2_Synagoge-Heidereuthergasse_innen_c-CJ-WAkl-2.jpg","contentUrl":"https:\/\/centrumjudaicum.de\/wp-content\/uploads\/1714\/09\/Bild-2_Synagoge-Heidereuthergasse_innen_c-CJ-WAkl-2.jpg","width":263,"height":263},{"@type":"BreadcrumbList","@id":"https:\/\/centrumjudaicum.de\/dies-ist-eine-ueberschrift-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/centrumjudaicum.de\/"},{"@type":"ListItem","position":2,"name":"7. September 1714 Einweihung Gemeindesynagoge Heidereutergasse"}]},{"@type":"WebSite","@id":"https:\/\/centrumjudaicum.de\/#website","url":"https:\/\/centrumjudaicum.de\/","name":"Centrum Judaicum","description":"","publisher":{"@id":"https:\/\/centrumjudaicum.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrumjudaicum.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/centrumjudaicum.de\/#organization","name":"Centrum Judaicum","url":"https:\/\/centrumjudaicum.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/centrumjudaicum.de\/#\/schema\/logo\/image\/","url":"https:\/\/centrumjudaicum.de\/wp-content\/uploads\/2022\/10\/Logo_Stiftung_Neue_Synagoge_Berlin_Gold_.png","contentUrl":"https:\/\/centrumjudaicum.de\/wp-content\/uploads\/2022\/10\/Logo_Stiftung_Neue_Synagoge_Berlin_Gold_.png","width":1188,"height":409,"caption":"Centrum Judaicum"},"image":{"@id":"https:\/\/centrumjudaicum.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/centrumjudaicum.de\/#\/schema\/person\/92a9897d9fc5452e4e01ff70c2fa760d","name":"wpadmin2","sameAs":["https:\/\/centrumjudaicum.de"],"url":"https:\/\/centrumjudaicum.de\/en\/author\/wpadmin2\/"}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/centrumjudaicum.de\/en\/wp-json\/wp\/v2\/posts\/1688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrumjudaicum.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrumjudaicum.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrumjudaicum.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/centrumjudaicum.de\/en\/wp-json\/wp\/v2\/comments?post=1688"}],"version-history":[{"count":3,"href":"https:\/\/centrumjudaicum.de\/en\/wp-json\/wp\/v2\/posts\/1688\/revisions"}],"predecessor-version":[{"id":15985,"href":"https:\/\/centrumjudaicum.de\/en\/wp-json\/wp\/v2\/posts\/1688\/revisions\/15985"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrumjudaicum.de\/en\/wp-json\/wp\/v2\/media\/15337"}],"wp:attachment":[{"href":"https:\/\/centrumjudaicum.de\/en\/wp-json\/wp\/v2\/media?parent=1688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrumjudaicum.de\/en\/wp-json\/wp\/v2\/categories?post=1688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrumjudaicum.de\/en\/wp-json\/wp\/v2\/tags?post=1688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}